{"id":1997,"date":"2008-04-25T12:43:17","date_gmt":"2008-04-25T06:43:17","guid":{"rendered":"http:\/\/nightmareonelmstreetfilms.com\/blog\/?p=176"},"modified":"2008-04-25T12:43:17","modified_gmt":"2008-04-25T06:43:17","slug":"black-flame-now-closed","status":"publish","type":"post","link":"https:\/\/nightmareonelmstreetfilms.com\/site\/black-flame-now-closed\/","title":{"rendered":"Black Flame now closed!"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/s23.photobucket.com\/albums\/b394\/nightmarewebmaster\/th_bflogo.jpg\" alt=\"Black Flame\" \/><strong>Black Flame<\/strong>, the latest New Line Cinema licensed novel publisher, has officially <a title=\"Black Flame website.\" href=\"http:\/\/www.blackflame.com\/\" target=\"_blank\">closed<\/a>.<\/p>\n<p>Black Flame published novels for many of New Line&#8217;s properties, specifically horror and Sci-Fi related, including <em>A Nightmare on Elm Street<\/em>, <em>Friday the 13th<\/em>, <em>Final Destination<\/em>, and more.<\/p>\n<p>Check out their Nightmare related novels by clicking <a title=\"Black Flame Nightmare on Elm Street novels.\" href=\"http:\/\/nightmareonelmstreetfilms.com\/forum\/viewtopic.php?t=11\">here<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Black Flame, the latest New Line Cinema licensed novel publisher, has officially closed. Black &hellip; <a href=\"https:\/\/nightmareonelmstreetfilms.com\/site\/black-flame-now-closed\/\" class=\"read-more\">Read more &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[45,48,141,199,211],"class_list":["post-1997","post","type-post","status-publish","format-standard","hentry","category-merchandise","tag-black-flame","tag-books","tag-house-of-horror","tag-new-line-cinema","tag-novels"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Administrator\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/nightmareonelmstreetfilms.com\/site\/black-flame-now-closed\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nightmareonelmstreetfilms.com\\\/site\\\/black-flame-now-closed\\\/#article\",\"name\":\"Black Flame now closed! | Nightmare on Elm Street Companion \\u2014 Ultimate Online Resource to Horror Series A Nightmare on Elm Street\",\"headline\":\"Black Flame now closed!\",\"author\":{\"@id\":\"https:\\\/\\\/nightmareonelmstreetfilms.com\\\/site\\\/author\\\/administrator\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/nightmareonelmstreetfilms.com\\\/site\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/s23.photobucket.com\\\/albums\\\/b394\\\/nightmarewebmaster\\\/th_bflogo.jpg\",\"@id\":\"https:\\\/\\\/nightmareonelmstreetfilms.com\\\/site\\\/black-flame-now-closed\\\/#articleImage\"},\"datePublished\":\"2008-04-25T12:43:17-07:00\",\"dateModified\":\"2008-04-25T12:43:17-07:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nightmareonelmstreetfilms.com\\\/site\\\/black-flame-now-closed\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/nightmareonelmstreetfilms.com\\\/site\\\/black-flame-now-closed\\\/#webpage\"},\"articleSection\":\"Merchandise, Black Flame, Books, House of Horror, New Line Cinema, Novels\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nightmareonelmstreetfilms.com\\\/site\\\/black-flame-now-closed\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nightmareonelmstreetfilms.com\\\/site#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nightmareonelmstreetfilms.com\\\/site\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nightmareonelmstreetfilms.com\\\/site\\\/category\\\/merchandise\\\/#listItem\",\"name\":\"Merchandise\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nightmareonelmstreetfilms.com\\\/site\\\/category\\\/merchandise\\\/#listItem\",\"position\":2,\"name\":\"Merchandise\",\"item\":\"https:\\\/\\\/nightmareonelmstreetfilms.com\\\/site\\\/category\\\/merchandise\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nightmareonelmstreetfilms.com\\\/site\\\/black-flame-now-closed\\\/#listItem\",\"name\":\"Black Flame now closed!\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nightmareonelmstreetfilms.com\\\/site#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nightmareonelmstreetfilms.com\\\/site\\\/black-flame-now-closed\\\/#listItem\",\"position\":3,\"name\":\"Black Flame now closed!\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nightmareonelmstreetfilms.com\\\/site\\\/category\\\/merchandise\\\/#listItem\",\"name\":\"Merchandise\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nightmareonelmstreetfilms.com\\\/site\\\/#organization\",\"name\":\"Nightmare on Elm Street Companion \\u2014 Ultimate Online Resource to Horror Series A Nightmare on Elm Street\",\"description\":\"A Nightmare on Elm Street Film Series Web Site\",\"url\":\"https:\\\/\\\/nightmareonelmstreetfilms.com\\\/site\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nightmareonelmstreetfilms.com\\\/site\\\/author\\\/administrator\\\/#author\",\"url\":\"https:\\\/\\\/nightmareonelmstreetfilms.com\\\/site\\\/author\\\/administrator\\\/\",\"name\":\"Administrator\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/nightmareonelmstreetfilms.com\\\/site\\\/black-flame-now-closed\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/31a5c69f5a640b42d222469cd82c98f8be10eacdc9dbdbb84b70cac8796687e2?s=96&d=mm&r=pg\",\"width\":96,\"height\":96,\"caption\":\"Administrator\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nightmareonelmstreetfilms.com\\\/site\\\/black-flame-now-closed\\\/#webpage\",\"url\":\"https:\\\/\\\/nightmareonelmstreetfilms.com\\\/site\\\/black-flame-now-closed\\\/\",\"name\":\"Black Flame now closed! | Nightmare on Elm Street Companion \\u2014 Ultimate Online Resource to Horror Series A Nightmare on Elm Street\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nightmareonelmstreetfilms.com\\\/site\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nightmareonelmstreetfilms.com\\\/site\\\/black-flame-now-closed\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/nightmareonelmstreetfilms.com\\\/site\\\/author\\\/administrator\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/nightmareonelmstreetfilms.com\\\/site\\\/author\\\/administrator\\\/#author\"},\"datePublished\":\"2008-04-25T12:43:17-07:00\",\"dateModified\":\"2008-04-25T12:43:17-07:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nightmareonelmstreetfilms.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/nightmareonelmstreetfilms.com\\\/site\\\/\",\"name\":\"Nightmare on Elm Street Companion \\u2014 Ultimate Online Resource to Horror Series A Nightmare on Elm Street\",\"description\":\"A Nightmare on Elm Street Film Series Web Site\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/nightmareonelmstreetfilms.com\\\/site\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Black Flame now closed! | Nightmare on Elm Street Companion \u2014 Ultimate Online Resource to Horror Series A Nightmare on Elm Street","description":"","canonical_url":"https:\/\/nightmareonelmstreetfilms.com\/site\/black-flame-now-closed\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nightmareonelmstreetfilms.com\/site\/black-flame-now-closed\/#article","name":"Black Flame now closed! | Nightmare on Elm Street Companion \u2014 Ultimate Online Resource to Horror Series A Nightmare on Elm Street","headline":"Black Flame now closed!","author":{"@id":"https:\/\/nightmareonelmstreetfilms.com\/site\/author\/administrator\/#author"},"publisher":{"@id":"https:\/\/nightmareonelmstreetfilms.com\/site\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/s23.photobucket.com\/albums\/b394\/nightmarewebmaster\/th_bflogo.jpg","@id":"https:\/\/nightmareonelmstreetfilms.com\/site\/black-flame-now-closed\/#articleImage"},"datePublished":"2008-04-25T12:43:17-07:00","dateModified":"2008-04-25T12:43:17-07:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/nightmareonelmstreetfilms.com\/site\/black-flame-now-closed\/#webpage"},"isPartOf":{"@id":"https:\/\/nightmareonelmstreetfilms.com\/site\/black-flame-now-closed\/#webpage"},"articleSection":"Merchandise, Black Flame, Books, House of Horror, New Line Cinema, Novels"},{"@type":"BreadcrumbList","@id":"https:\/\/nightmareonelmstreetfilms.com\/site\/black-flame-now-closed\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/nightmareonelmstreetfilms.com\/site#listItem","position":1,"name":"Home","item":"https:\/\/nightmareonelmstreetfilms.com\/site","nextItem":{"@type":"ListItem","@id":"https:\/\/nightmareonelmstreetfilms.com\/site\/category\/merchandise\/#listItem","name":"Merchandise"}},{"@type":"ListItem","@id":"https:\/\/nightmareonelmstreetfilms.com\/site\/category\/merchandise\/#listItem","position":2,"name":"Merchandise","item":"https:\/\/nightmareonelmstreetfilms.com\/site\/category\/merchandise\/","nextItem":{"@type":"ListItem","@id":"https:\/\/nightmareonelmstreetfilms.com\/site\/black-flame-now-closed\/#listItem","name":"Black Flame now closed!"},"previousItem":{"@type":"ListItem","@id":"https:\/\/nightmareonelmstreetfilms.com\/site#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/nightmareonelmstreetfilms.com\/site\/black-flame-now-closed\/#listItem","position":3,"name":"Black Flame now closed!","previousItem":{"@type":"ListItem","@id":"https:\/\/nightmareonelmstreetfilms.com\/site\/category\/merchandise\/#listItem","name":"Merchandise"}}]},{"@type":"Organization","@id":"https:\/\/nightmareonelmstreetfilms.com\/site\/#organization","name":"Nightmare on Elm Street Companion \u2014 Ultimate Online Resource to Horror Series A Nightmare on Elm Street","description":"A Nightmare on Elm Street Film Series Web Site","url":"https:\/\/nightmareonelmstreetfilms.com\/site\/"},{"@type":"Person","@id":"https:\/\/nightmareonelmstreetfilms.com\/site\/author\/administrator\/#author","url":"https:\/\/nightmareonelmstreetfilms.com\/site\/author\/administrator\/","name":"Administrator","image":{"@type":"ImageObject","@id":"https:\/\/nightmareonelmstreetfilms.com\/site\/black-flame-now-closed\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/31a5c69f5a640b42d222469cd82c98f8be10eacdc9dbdbb84b70cac8796687e2?s=96&d=mm&r=pg","width":96,"height":96,"caption":"Administrator"}},{"@type":"WebPage","@id":"https:\/\/nightmareonelmstreetfilms.com\/site\/black-flame-now-closed\/#webpage","url":"https:\/\/nightmareonelmstreetfilms.com\/site\/black-flame-now-closed\/","name":"Black Flame now closed! | Nightmare on Elm Street Companion \u2014 Ultimate Online Resource to Horror Series A Nightmare on Elm Street","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/nightmareonelmstreetfilms.com\/site\/#website"},"breadcrumb":{"@id":"https:\/\/nightmareonelmstreetfilms.com\/site\/black-flame-now-closed\/#breadcrumblist"},"author":{"@id":"https:\/\/nightmareonelmstreetfilms.com\/site\/author\/administrator\/#author"},"creator":{"@id":"https:\/\/nightmareonelmstreetfilms.com\/site\/author\/administrator\/#author"},"datePublished":"2008-04-25T12:43:17-07:00","dateModified":"2008-04-25T12:43:17-07:00"},{"@type":"WebSite","@id":"https:\/\/nightmareonelmstreetfilms.com\/site\/#website","url":"https:\/\/nightmareonelmstreetfilms.com\/site\/","name":"Nightmare on Elm Street Companion \u2014 Ultimate Online Resource to Horror Series A Nightmare on Elm Street","description":"A Nightmare on Elm Street Film Series Web Site","inLanguage":"en-US","publisher":{"@id":"https:\/\/nightmareonelmstreetfilms.com\/site\/#organization"}}]}},"aioseo_meta_data":{"post_id":"1997","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-02-13 11:42:39","updated":"2022-12-24 16:37:18","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"_links":{"self":[{"href":"https:\/\/nightmareonelmstreetfilms.com\/site\/wp-json\/wp\/v2\/posts\/1997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nightmareonelmstreetfilms.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nightmareonelmstreetfilms.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nightmareonelmstreetfilms.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nightmareonelmstreetfilms.com\/site\/wp-json\/wp\/v2\/comments?post=1997"}],"version-history":[{"count":0,"href":"https:\/\/nightmareonelmstreetfilms.com\/site\/wp-json\/wp\/v2\/posts\/1997\/revisions"}],"wp:attachment":[{"href":"https:\/\/nightmareonelmstreetfilms.com\/site\/wp-json\/wp\/v2\/media?parent=1997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nightmareonelmstreetfilms.com\/site\/wp-json\/wp\/v2\/categories?post=1997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nightmareonelmstreetfilms.com\/site\/wp-json\/wp\/v2\/tags?post=1997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}